{"id":11130,"date":"2021-02-23T16:13:00","date_gmt":"2021-02-23T16:13:00","guid":{"rendered":"https:\/\/nova.rutesentrerefugis.com\/?p=11130"},"modified":"2023-10-31T08:32:17","modified_gmt":"2023-10-31T08:32:17","slug":"la-vuelta-a-la-tinenca-de-benifassa","status":"publish","type":"post","link":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/","title":{"rendered":"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11130\" class=\"elementor elementor-11130\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95df28b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"95df28b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84065af\" data-id=\"84065af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c09c1a0 elementor-widget elementor-widget-image\" data-id=\"c09c1a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"450\" src=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Cap.jpg\" class=\"attachment-full size-full wp-image-11090\" alt=\"\" srcset=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Cap.jpg 2000w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Cap-300x68.jpg 300w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Cap-1024x230.jpg 1024w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Cap-768x173.jpg 768w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Cap-1536x346.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2db30a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c2db30a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7702d15\" data-id=\"7702d15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6bdcec elementor-widget elementor-widget-heading\" data-id=\"d6bdcec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4773d0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d4773d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8be536\" data-id=\"a8be536\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b5d92c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7b5d92c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88c38ed elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"88c38ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27365fc\" data-id=\"27365fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8716c3 elementor-widget elementor-widget-spacer\" data-id=\"a8716c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22508a8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"22508a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f16c46\" data-id=\"4f16c46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b239672 elementor-widget elementor-widget-heading\" data-id=\"b239672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LA ESQUISITEZ DEL BAIX MAESTRAT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d03fa05 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d03fa05\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c4e6e7c\" data-id=\"c4e6e7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9b0e54 elementor-widget elementor-widget-text-editor\" data-id=\"c9b0e54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Cr\u00f3nica escrita por IGNASI PLANAS DE MART\u00cd y publicada en la revista MUNTANYA n\u00famero 898<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df088b6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"df088b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-298e764\" data-id=\"298e764\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e13bf9 elementor-widget elementor-widget-text-editor\" data-id=\"8e13bf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><span style=\"color: #158e45;\">Un circuito de monta\u00f1a que recorre en tres jornadas las villas de esta regi\u00f3n solitaria del norte del Baix Maestrat. El primer d\u00eda subimos a Fredes y, por el Tossal dels Tres Reis llegamos al Boixar. El segundo d\u00eda pasamos por Coratx\u00e0 y Castell de Cabres, para terminar en Vallibona. La \u00faltima jornada nos acerca a la Pobla de Benifass\u00e0 y al Ballestar.<\/span><\/h5>\n<h5>La Tinen\u00e7a de Benifass\u00e0 es una regi\u00f3n ignota para la mayor\u00eda de caminantes y amantes de la naturaleza. Arrinconada m\u00e1s all\u00e1 de las abruptas monta\u00f1as del Port, dispone todav\u00eda de algunos rincones arbolados y de profundos barrancos. Hacia poniente y en los confines septentrionales se amplifica en lomas extensas y colinas calc\u00e1reas, de vegetaci\u00f3n rasa donde abundan los bancales de hierba, los caminos ganaderos y las grandes mas\u00edas. Son tierras altas, fr\u00edas y de amplios horizontes, que se hermanan con los paisajes morellanos y del Alt Maestrat.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0ec3ef elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e0ec3ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3164d6b\" data-id=\"3164d6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57ab367 elementor-widget elementor-widget-image\" data-id=\"57ab367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2000\" height=\"1000\" src=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-01.jpg\" class=\"attachment-full size-full wp-image-11089\" alt=\"\" srcset=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-01.jpg 2000w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-01-300x150.jpg 300w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-01-1024x512.jpg 1024w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-01-768x384.jpg 768w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-01-1536x768.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Fredes, pueblo del municipio de la Pobla de Benifass\u00e0, situado en el centro del peque\u00f1o altiplano de la hoya de Fredes (\u00a9 Josep Lorman)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14c34de elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"14c34de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5db3393\" data-id=\"5db3393\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d2eb3e elementor-widget elementor-widget-text-editor\" data-id=\"0d2eb3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Este territorio adusto tambi\u00e9n refleja una evidente gradaci\u00f3n clim\u00e1tica: la parte baja y pr\u00f3xima al r\u00edo S\u00e9nia, donde est\u00e1 la Pobla de Benifass\u00e0, el Bellestar y el monasterio de Benifass\u00e0 tiene una luminosidad mediterr\u00e1nea y encontramos pinares de pino blanco y cultivos de almendros. A medida que nos adentramos y ganamos altitud, abarcamos las mesetas abanicadas y las conjuntos ardidos, donde se recortan n\u00edtidamente los m\u00e1rgenes infinitos de piedra seca y las sinuosidades ajustadas de los viejos caminos pecuarios. Todav\u00eda quedan manchas arboladas de encinas, pinos negrales y albares, y de robles escasos. Es terreno de los grandes y solitarias masias, casi todos polvorientos, y de los pueblos m\u00e1s elevados del Pa\u00eds Valenci\u00e0: Bel, Fredes, Boixar, Coratx\u00e0 y Castell de Cabres.<\/br>\n<\/br>\nJunto a las tierras de la Tinen\u00e7a est\u00e1 el t\u00e9rmino de Vallibona, con la pintoresca poblaci\u00f3n ajustada en el fondo valle del r\u00edo Cervol. Una parte de todo este vasto territorio se incluye dentro del parque natural de la Tinen\u00e7a de Benifass\u00e0 y otras figuras de protecci\u00f3n de la naturaleza. La totalidad de superficie de los t\u00e9rminos municipales sobrepasa los 300 km2. La densidad de poblaci\u00f3n es \u00ednfima y ni tal s\u00f3lo alcanza 1 hab\/km2.<\/h5>\n&nbsp;\n<h4><span style=\"color: #000000;\"><u>LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0<\/u><\/span><\/h4>\n<h5>La vuelta a la Tinen\u00e7a de Benifass\u00e0 es un completo circuito que recorre en tres jornadas toda esta magn\u00edfica comarca monta\u00f1osa, utilizando la densa red de caminos se\u00f1alizados y otros de arreglados \u00faltimamente por los servicios del parque natural. Se aprovechan los pueblos para pasar la noche y tambi\u00e9n para hacer la comida del mediod\u00eda, as\u00ed podremos caminar con m\u00e1s comodidad y al mismo tiempo disfrutar de la gastronom\u00eda aut\u00f3ctona. El inicio y final del recorrido es en el embalse de Ulldecona. El primer d\u00eda se sube a Fredes y por el Tossal dels Tres Reis se llega al Boixar. El segundo d\u00eda se pasa por Coratx\u00e0 y Castell de Cabres y se finaliza en Vallibona. Finalmente, la \u00faltima jornada nos acerca a la Pobla de Benifass\u00e0 y el Bellestar. S\u00f3lo queda fuera del circuito el peque\u00f1o mas de Bel: aunque se vislumbra cercano, queda m\u00e1s alejado de nuestro itinerario. En conjunto habremos hecho unos 80 km de camino, 2.000 m de subida, y un total de 21,5 h de marcha efectiva.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcb5925 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dcb5925\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28b939e\" data-id=\"28b939e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1ea501 elementor-widget elementor-widget-text-editor\" data-id=\"f1ea501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #b40404;\">PRIMERA ETAPA<\/span><\/h4><h4><span style=\"color: #000000;\"><u>DEL EMBALSE DE ULLDECONA AL BOIXAR,<br \/>POR FREDES Y EL TOSSAL DELS TRES REIS<\/u><\/span><\/h4><h6><b>Tiempo de camino:<\/b> 7 h 30 min<br \/><b>Desnivel:<\/b> +1.000 m<\/h6><h5><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Embassament d&#8217;Ulldecona (477 m)<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Mas d&#8217;Abella (530 m): 0:35 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Portell de l&#8217;Infern (964 m): 1:15 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Fredes (1.095 m): 0:50 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Pinar Pla (1.164 m): 0:50 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Tossal dels Tres Reis (1.351 m): 0:25 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Serra Pelada (1.333 m): 0:25 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Mas Blanc (1.186 m): 0:45 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Mas de l&#8217;Hostalet (980 m): 0:45 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> El Boixar (1.089 m): 0:45 h<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-159346b\" data-id=\"159346b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-781f477 elementor-widget elementor-widget-text-editor\" data-id=\"781f477\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #000000;\"><u>EL PORTELL DE L&#8217;INFERN Y EL TOSSAL DELS TRES REIS: DE LOS ACANTILADOS CALC\u00c1REOS A LAS LOMAS ELEVADAS<\/u><\/span><\/h4>\n<h5>Se sale del embalse de Ulldecona por la carretera de tierra de los Magraners que, hacia el norte, sigue a cierta altura la orilla de este pantano. Las aguas quietas y azuladas reflejan los contornos de las monta\u00f1as que la rodean. En el trasfondo, por encima de los relieves rotos del barranco de la Fou, est\u00e1 la cresta emboscada del Negrell, una de las cimas m\u00e1s elevadas del macizo del Port. Este apacible paisaje nos acompa\u00f1a hasta decantarnos por el camino que asciende a la pr\u00f3xima masia de Abella, menuda edificaci\u00f3n blanqueada y emplazada en las repisas de los riscos. Las se\u00f1ales del PR CV-75.1 se encuentran muy desdibujados. Enfilamos la vieja senda transitada que conserva pedazos cuidadosamente empedrados. Giramos por el risco y penetramos en un hondonada escondida. Mudamos de direcci\u00f3n para meternos hacia dentro del pinar majestuoso donde destacan algunos grandes ejemplares de pinos negrales. Subimos decididamente a encontrar el paso que hay en las rocas resquebrajadas que da nombre al portillo del Infern.<\/br>\n<\/br>\nNos encontramos en un singular paraje donde los acantilados calc\u00e1reos forman grutas y roquedales aislados. El sendero circula aferrado a la roca en un tramo sumamente sugestivo. Un promontorio avanzado nos permite captar a vuelo de p\u00e1jaro de una espectacular perspectiva de la barrancada salvaje del Salt. Continuamos la ascensi\u00f3n y pasamos junto a las ruinas del maset del Pixon, con una bella era circular.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9bea6b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e9bea6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24a179f\" data-id=\"24a179f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bbdfd9 elementor-widget elementor-widget-text-editor\" data-id=\"9bbdfd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Transponemos la cresta y bajamos entre bosque a la hoya de Fredes. Las casas acurrucadas a la aldea se separan solitarias entre los bancales de pastoreo y las manchas emboscadas. En el pico de invierno son muy frecuentes las bajas temperaturas y la nieve. La etimolog\u00eda del top\u00f3nimo nos se\u00f1ala esta crudeza clim\u00e1tica. Seg\u00fan el fil\u00f3logo Joan Coromines, Fredes proviene del lat\u00edn fr\u00edgida, en relaci\u00f3n a la dispersi\u00f3n de lujo o &#8216;villas fr\u00edgidas&#8217; que hay en este elevado territorio. A partir de Fredes nos adentramos por comarcas esquivas y solitarias, totalmente despobladas.<\/br>\n<\/br>\nSeguimos las trazas del GR 7 en direcci\u00f3n al pinar Pla. El camino transcurre muy atractivo entre m\u00e1rgenes de piedra seca y, m\u00e1s all\u00e1, bajo la sombra protectora del carrascal. La mirada se pierde hacia la hondonada del Salt y la cumbre de la colina de Cervera, debajo del cual aparece, empeque\u00f1ecido por la distancia, el mas del Peraire. En el pinar Pla abandonamos el GR 7 y, cruzando la carretera forestal, bajamos por los bancalets hasta el destartalado edificio del Mas del R\u00edo de Fredes. Por detr\u00e1s, tomamos hacia la izquierda el camino ancho que a continuaci\u00f3n bifurca. El ramal de la izquierda nos acerca arriba del Tossal dels Tres Reis.<\/br>\n<\/br>\nArriba del Tossal dels Tres Reis, a 1.351 m, se re\u00fanen Arag\u00f3n, Catalu\u00f1a y Valencia, en medio de un extensa comarca monta\u00f1osa donde se habla la misma lengua y con unos rasgos culturales comunes. Un moj\u00f3n trifinio deja constancia. La panor\u00e1mica que se otea es circular. La mirada se pierde por monta\u00f1oso escabroso del Port hasta sus confines levantinos donde destaca la cima del Caro. A Poniente, los bosques son m\u00e1s espor\u00e1dicos y dejan paso a las lomas con hierba y los cerros rocosos de la Tinen\u00e7a. El m\u00e1s cercano es el cerro de Canad\u00e9 que con sus 1.393 m representa la m\u00e1xima altitud de la regi\u00f3n. A sus pies, queda escondido el mas Blanc hacia d\u00f3nde nos debemos dirigir. Al norte se nos abre infinita la llanura del Bajo Arag\u00f3n por donde campan una serie de pueblos.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d883b0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2d883b0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1e3e69\" data-id=\"b1e3e69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8092e3 elementor-widget elementor-widget-image\" data-id=\"a8092e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2000\" height=\"1055\" src=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-02.jpg\" class=\"attachment-full size-full wp-image-11095\" alt=\"\" srcset=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-02.jpg 2000w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-02-300x158.jpg 300w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-02-1024x540.jpg 1024w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-02-768x405.jpg 768w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-02-1536x810.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Pant\u00e0 d'Ulldecona, escenari de l'inici i final de la volta a la Tinen\u00e7a de Benifass\u00e0 (\u00a9 Josep Lorman)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7a90e4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d7a90e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-153c029\" data-id=\"153c029\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d152be4 elementor-widget elementor-widget-text-editor\" data-id=\"d152be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #000000;\"><u>LOS RELLANOS DEL MAS BLANC Y LA DEPRESI\u00d3N DEL BOIXAR:<\/br>\nMAS\u00cdAS RUINOSAS Y SOLITARIAS<\/u><\/span><\/h4>\n<h5>Seguimos la cumbre de la colina de los Tres Reis hacia el oeste y llegamos el ancho camino que por la derecha lleva a Sant Miguel d&#8217;Espinalbar. En direcci\u00f3n contraria bajamos suavemente, abandonamos el desv\u00edo vallado del mas de Fontsanta y antes de un recodo pronunciado, aprovechamos un atajo que por la derecha y por encima la pista, conecta con un cresta rocosa. Lo seguimos por un d\u00e9bil sendero que nos deja en unos bancales emboscados. Entonces, sin perder altura, vamos en direcci\u00f3n norte hasta llegar a la pista del Mas Blanc, cerca de un charco de agua y de la cota 1.333 m de la sierra Pelada.<\/br>\n<\/br>\nSeguimos la pista de la sierra Pelada descendiendo por la larga loma desarbolada, coloreada en primavera por una multitud de flores y plantas arom\u00e1ticas. A lo lejos se vislumbra el pueblo de El Boixar. Hacemos hacia la ancha collada recortada por hileras de m\u00e1rgenes que ordenan los antiguos bancales del Mas Blanc. Aqu\u00ed abandonamos la pista que por el collado de la Barraca y el tossal del Hereu llega al pueblo de Pena-roja. Utilizamos el camino viejo para ir al pozo de agua del mas Blanc, construido en un margen y, cruzando la coma, llegamos a los edificios del grandioso mas Blanc.<\/br>\n<\/br>\nEl mas Blanc es seguramente el mejor ejemplo del patrimonio arquitect\u00f3nico rural de toda la Tinen\u00e7a de Benifass\u00e0, a pesar de su penoso estado de abandono. Los edificios forman una hilera de casas de estructura heterog\u00e9nea, encarados al sur. Una explanada cubierta de hierba con otras edificaciones medio derruidas completan este singular conjunto arquitect\u00f3nico, emplazado en un lugar solitario y sumamente sugestivo. Continuamos por la loma en direcci\u00f3n sur y encontramos un colada que acaba perdi\u00e9ndose. Unos hitos nos ayudan a bajar, primero en zigzag y luego en diagonal, por un sendero r\u00e1pido hasta cruzar el barranco de Les Comes.<\/br>\n<\/br>\nPor la otra vertiente transita una pista y el PR CV-75 12 que proviene de Fredes. Lo seguimos en subida y saltamos al surco del barranco de la Canal, que es la cabecera del r\u00edo de los Prats. Antes del corral de Andreu, dejamos la pista y bajamos fuerte hasta por otra pista justo en el punto donde hay una valla que impide el paso de los veh\u00edculos. Abandonamos el PR y traspasamos la valla. Estamos en el cauce ancho y seco del barranco. El camino que lo recorre hacia arriba nos lleva al Mas del Hostalet y, un poco m\u00e1s all\u00e1, a la conexi\u00f3n con el GR 7. Entre bancales de hierba y algunos cultivos, el ancho camino nos acerca al Boixar. Por la fuente y el lavadero del pueblo se alcanzan la parte baja de la poblaci\u00f3n. El Boixar es un pueblo acogedor, formado por callejuelas paralelas que ocupan la vertiente soleada de una colina. Casi en lo alto est\u00e1 la iglesia de proporciones considerables, con un corpulento campanario.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a91f92d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a91f92d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ea1b37c\" data-id=\"ea1b37c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aae8e06 elementor-widget elementor-widget-text-editor\" data-id=\"aae8e06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #b40404;\">SEGUNDA ETAPA<\/span><\/h4><h4><span style=\"color: #000000;\"><u>DEL BOIXAR A VALLIBONA, POR CORATX\u00c0 Y CASTELL DE CABRES<\/u><\/span><\/h4><h6><b>Tiempo de camino:<\/b> 7 h 30 min<br \/><b>Desnivel:<\/b> +5.000 m<\/h6><h5><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Coratx\u00e0 (1.235 m): 1:10 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> La Puntassa (1.345 m): 0:45 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Font de Catxo (1.230 m): 0:50 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Sant Crist\u00f2fol (1.252 m): 0:35 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Riu Escalona (960 m): 0:50 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Castell de Cabres (1.129 m): 0:40 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Mas de Boix (1.110 m): 0:45 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Mas de Cardona (960 m): 0:20 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Ullals de la Gatellera (770 m): 1:00 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Vallibona (683 m): 0:45 h<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1f251ed\" data-id=\"1f251ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c01094a elementor-widget elementor-widget-text-editor\" data-id=\"c01094a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #000000;\"><u>CORATX\u00c0 Y CASTELL DE CABRES, POR SENDAS Y MESETAS ABANICADAS<\/u><\/span><\/h4>\n<h5>Salimos del Boixar por la parte alta donde hay un poste indicador del sendero PR CV-75 11 que conduce a Coratx\u00e0. Cruzamos la carretera y hacemos un largo trozo de sendero, metidos en el barranco sombr\u00edo. Menudean los bojes, restos de los bojedales que dieron nombre al pueblo y que seg\u00fan Pascual Madoz, en su diccionario de mediados del siglo XIX, se encontraban en el NO de la poblaci\u00f3n. Ascendemos hacia la sierra de las Albades.<\/br>\n<\/br>\nAtravesamos el asfalto por segunda vez y planeamos por los altos de la sierra entre noveles plantaciones forestales. Despu\u00e9s, bajamos hasta la hondonada de la Ballestera, teniendo frente una bella perspectiva de la encumbrada aldea de Coratx\u00e0. Por \u00faltima vez cruzamos la carretera y ascendemos derechamente por un colada herbosa hasta esta peque\u00f1a poblaci\u00f3n. La sombra de un gran tilo y la pr\u00f3xima fuente, nos invitan a descansar en un banco de la plaza.<\/br>\n<\/br>\nNos acercamos a la iglesia de Sant Jaume, aislada sobre una colina entre praderas verdeantes, y dominando el vasto territorio de la Tinen\u00e7a. En la cima del lado est\u00e1 el peir\u00f3 (o pigra) de Sant Jaume. Seg\u00fan Joan Coromines, Coratx\u00e0 proviene del \u00e1rabe qurac\u00e2ni, palabra alusiva a dos Coratx\u00e0 (corazas), fortificaciones o murallas protectoras que coronaban los dos cerros gemelos.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d87def elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5d87def\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb15400\" data-id=\"bb15400\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aac2086 elementor-widget elementor-widget-image\" data-id=\"aac2086\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1171\" src=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-03.jpg\" class=\"attachment-full size-full wp-image-11112\" alt=\"\" srcset=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-03.jpg 2000w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-03-300x176.jpg 300w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-03-1024x600.jpg 1024w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-03-768x450.jpg 768w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-03-1536x899.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">El camino pasa a tocar de la iglesia de Coratx\u00e0 (\u00a9Josep Lorman)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-692726f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"692726f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4829feb\" data-id=\"4829feb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f24e76 elementor-widget elementor-widget-text-editor\" data-id=\"2f24e76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Bajamos por el otro costero al encuentro de un atajo que nos lleva a continuaci\u00f3n a la ancha pista por donde pasa el PRCV-75 8 y la ruta de la Rogativa Vallibona &#8211; Pena-roja. La cruzamos en perpendicular y remontamos la costa por un destartalada ca\u00f1ada que rodea la cima de la Solana. Por la vaguada arriba sigue un sendero y casi en lo alto enlazamos con una pista cuando estamos muy cercanos a la fuente Freda. La seguimos por la izquierda y nos plantamos arriba del collado asolado donde hay, borde a una peque\u00f1a caseta, un enforcadura de caminos: a la derecha hacia Pena-roja, a la izquierda en el cabezal de la mola de Mitjavila. Seguimos este \u00faltimo hasta alcanzar el v\u00e9rtice geod\u00e9sico de la Puntassa, fant\u00e1stica miranda encarada en la comarca del Matarra\u00f1a. Justo por debajo, en un rinc\u00f3n fresco y rodeada de despe\u00f1aderos, est\u00e1 la cueva de la Puntassa.<\/br>\n<\/br>\nRetrocedemos sin llegar a la bifurcaci\u00f3n antes mencionada y nos desviamos por unas roderas que recorren la mola de Mitjavila, en direcci\u00f3n SO. Pasamos rozando la boca de la sima del Ase. En su interior, encontraremos estalagmitas y agujeros que nos sorprender\u00e1n gratamente. Continuamos por la loma disfrutando de excelentes panor\u00e1micas, hasta que el camino se desdibuja y se pierde, momento en que nos decantaremos a la izquierda para bajar por el fondo del peque\u00f1o valle abancalado donde est\u00e1 el maset del Cinto. Despu\u00e9s de todo llegamos a la confluencia de la pista de la mola de Mitjavila con la del PR CV-75 8.<\/br>\n<\/br>\nPara esta \u00faltima ruta, hacia Poniente, vamos siguiendo la plana y en breve ascenso encontramos la fuente del Catxo. Hacemos una lazada para conseguir la larga loma de la sierra de Sant Crist\u00f2fol. Continuamos por el camino que la recorre de punta a punta, disfrutando en todo momento de vistas soberbias. Por debajo y muy pr\u00f3ximo est\u00e1 el solitario corral de Vilalta, en medio de un hoyo herbado, cerrado por acantilados calc\u00e1reos. Finalmente llegamos al extremo occidental de la sierra donde se aferran desamparadas las ruinas de la ermita de Sant Crist\u00f2fol. Se otea pr\u00f3ximo el pueblo de Herbeset y m\u00e1s all\u00e1, las monta\u00f1as de los puertos de Morella.<\/br>\n<\/br>\nRetrocedemos un poco para encontrar el paso de bajada al mas de Vilalta, se\u00f1alado con un gran hito y un poste indicador. La senda pierde altura velozmente por un grado y luego dentro del carrascal, hasta dejarnos cercanos al magn\u00edfico mas de Vilalta. Los edificios polvorientos se encuentran emplazados en un lugar cautivador, son de una arquitectura arm\u00f3nica y de una sobriedad imponente.<\/br>\n<\/br>\nVolvemos al PR V-75 8 y flanqueamos en diagonal la ladera por bancales abandonados. No tardamos en bajar por un bonito grado rocoso. Dentro del bosque sombr\u00edo, abarcamos la pista poco transitada que nos llevar\u00e1 hasta Lo Maset, todo desterrando el PR que sigue recto hacia Castell de Cabres. Sublevando la vertiente, nos plantamos en Lo Maset. Puestos ante su fachada, nos damos cuenta de la fisonom\u00eda humilde de este edificio perdido en los confines m\u00e1s rec\u00f3nditos de la Tinen\u00e7a. De estructura poco sobresaliente, destaca un bello balc\u00f3n amaderado. El bosque y los acantilados rodean el edificio solitario. De la parte delantera de la casa nace la vieja senda que baja hasta el lecho mismo del r\u00edo Escalona. Enfrente destaca una esbelta punta caliza. Es un lugar agradable y fresco, con las aguas del arroyo que forman peque\u00f1os charcos.<\/br>\n<\/br>\nCruzamos el cauce y conectamos con el inicio del sendero que monta hacia Castell de Cabres por el ahondado y emboscado barranco de la Saltadora. El recorrido es muy atractivo, circulando entre las rocas y el arbolado frondoso que crece en este hondonada. Arriba reunimos la senda principal por donde transita el PR que hemos dejado despu\u00e9s del mas de Vilalta. Encontramos a\u00fan trozos que conservan el empedrado original. En lo alto nos plantamos en el collado de detr\u00e1s de la colina de Castell de Cabres. A continuaci\u00f3n llegamos a esta poblaci\u00f3n, construida en las mesetas m\u00e1s occidentales de la Tinen\u00e7a.<\/h5>\n<\/br>\n<h4><span style=\"color: #000000;\"><u>EL BARRANCO DE LA GATELLERA Y VALLIBONA, EL PUEBLO ACURRUCADO BAJO LOS RISCOS<\/u><\/span><\/h4>\n<h5>Salimos de Castell de Cabres paralelos a la carretera, por el camino que baja hacia levante por la comalada. Encontramos unos pinos negrales excepcionales, los pinos de la Coveta, con un hermoso ramaje. En la confluencia de barrancos, dejamos el PR y seguimos el camino en direcci\u00f3n sur. Cruzamos la carretera y en perpendicular enfilamos la ancha ruta arreglada que lleva a Vallibona. Atravesamos el ordenado bosque p\u00fablico del Boveral. Despu\u00e9s de un corto tramo cementado, logramos en subida el collado donde hay una trifurcaci\u00f3n de itinerarios. Tomamos el desv\u00edo de la izquierda que rodea el cerro y nos lleva a la explanada del Mas de Boix, donde hay un excelente mirador encarado a los barrancos que se asoman a la inmenso valle del r\u00edo Cervol. Las monta\u00f1as del horizonte forman la extensa sierra de Turmell.<\/br>\n<\/br>\nPasamos a ras de los edificios desordenados del Mas de Boix y por unos pelda\u00f1os bajamos al reguero de la fuente. Llegamos al ancho camino que baja por el carrascal que cubre completamente la hondonada. En la pr\u00f3xima bifurcaci\u00f3n tomamos el ramal de la derecha y pronto subimos un sendero que baja hasta la era aislada y la ruinas del mas de Cardona. Los hitos nos ayudan a encontrar el paso de bajada que nos lleva al fondo mismo del barranco. En este punto obviamos la senda m\u00e1s transitada y seguimos por el borde del cauce del barranco. Salvamos una corta garganta y en diagonal conectamos con el GR 7 que transita por el fondo del espl\u00e9ndido y salvaje barranco de la Gatellera.<\/br>\n<\/br>\nAguas abajo el sendero se adentra en el pinar sombr\u00edo. Sin embargo, la traza no tarda en diluirse en el guijarral del cauce del barranco que hace m\u00e1s penosa la marcha. El lugar es agreste y escabroso en extremo, los estrechos de la Gatellera forman unas gargantas sinuosas muy atractivas y espectaculares. Luego, llegamos a los rodales m\u00e1s humanizados del mas Bordet. Encima, disimulado, est\u00e1 el mas de la Gatellera. M\u00e1s all\u00e1 de los bancales encontramos un paso ancho que nos lleva a los colmillos de la Gatellera, nacimiento de agua que se canaliza hasta Vallibona. Enlazamos con la ruta arreglada que baja en largos rodeos de Castell de Cabres. Estamos en el plano riscoso del mas del Grau. La perspectiva del hundida Vallibona detr\u00e1s de los acantilados que cierran el barranco es soberbia. Continuamos por el camino viejo que baja por un grado y ahorra una lazada de la pista. Por esta ruta asfaltada penetramos en la parte alta del pueblo de Vallibona.<\/br>\n<\/br>\nEl acopio de casas de Vallibona es muy pintoresco. Sin duda es el pueblo m\u00e1s bonito del recorrido. Sus calles bajan hasta el r\u00edo Cervol, donde bajo la sombra de la arboleda y muy cerca de las aguas est\u00e1 la fuente Vella. Los edificios se encuentran arreglados y algunos decorados con motivos tradicionales. La fisonom\u00eda del conjunto urbano es diferente de las aldeas de la Tinen\u00e7a, denota un car\u00e1cter m\u00e1s mediterr\u00e1neo y un clima menos fr\u00edo. Precisamente, el top\u00f3nimo Vallibona es el ant\u00f3nimo de Vallivana que significa &#8216;valle vac\u00edo&#8217;, lugar cercano con un llamado santuario que se encuentra en el t\u00e9rmino de Morella, en la otra vertiente de la sierra de Turmell.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4579d36 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4579d36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-010a63a\" data-id=\"010a63a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e250139 elementor-widget elementor-widget-image\" data-id=\"e250139\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1298\" src=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-04.jpg\" class=\"attachment-full size-full wp-image-11122\" alt=\"\" srcset=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-04.jpg 2000w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-04-300x195.jpg 300w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-04-1024x665.jpg 1024w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-04-768x498.jpg 768w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-04-1536x997.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Vista de Villabona, desde el Mas del Grau (\u00a9 Josep Lorman)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d5a695 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1d5a695\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15d70da\" data-id=\"15d70da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-971a385 elementor-widget elementor-widget-text-editor\" data-id=\"971a385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #b40404;\">TERCERA ETAPA<\/span><\/h4><h4><span style=\"color: #000000;\"><u>DE VALLIBONA A EL EMBALSE DE ULLDECONA,<br \/>POR EL MAS DE LES PRUNERES Y LA POBLA DE BENIFASS\u00c0<\/u><\/span><\/h4><h6><b>Tiemp ode camino:<\/b> 7 h<br \/><b>Desnivel:<\/b> +5.000 m<\/h6><h5><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Estrets de la Gatellera (830 m): 1:00 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Mas de Prades (964 m): 0:45 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Mas de les Pruneres (960 m): 0:50 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> La Creu (1.128 m): 0:25 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Coll del Xumador (996 m): 0:45 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> La Pobla de Benifass\u00e0 (701 m): 0:50 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> El Bellestar (713 m)<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Els Estrets (600 m): 0:45 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Forn de Vidre (500 m): 1:10 h<br \/><span style=\"color: #b40404;\"><b>\u00b7<\/b><\/span> Embassament d&#8217;Ulldecona (477 m): 0:30 h<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-527cec2\" data-id=\"527cec2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70d3118 elementor-widget elementor-widget-text-editor\" data-id=\"70d3118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #000000;\"><u>LA SENDA DEL MAS DE LES PRUNERES Y DE LA SERRA DE LA CREU<\/u><\/span><\/h4>\n<h5>Debemos deshacer el camino siguiendo aguas arriba el barranco de la Gatellera, pasamos por los Estrets y dejamos el sendero del mas de Cardona. Barranco arriba, seguimos las se\u00f1ales del GR 7. El pinar nos acompa\u00f1a sombreando el camino hasta la vista del mas de Prades, emplazado en lo alto de una loma que nos ofrece una espl\u00e9ndida panor\u00e1mica del barranco de la Teuleria y la sierra de Turmell. Justo encima del mas, nace disimulada la fant\u00e1stica senda que enlaza los diferentes masets, ahora todos polvorientos, que se emplazan en la ladera, a media altura de la barrancada. Hasta el mas de las Pruneres transitaremos por uno de los caminos m\u00e1s impresionantes de todo el recorrido. De primero perdemos altura y pasamos bajo unas carrascas monumentales, despu\u00e9s flanqueamos por encima el mas de las Saleres y, finalmente, ascendemos hacia el rec\u00f3ndito mas de les Pruneres. Este edificio cautivador queda metido en la cabecera del barranco y debajo la altiva y arisca umbr\u00eda de la sierra de la Creu.<\/br>\n<\/br>\nM\u00e1s all\u00e1 del mas de las Pruneres el camino viejo est\u00e1 frondoso y seguimos por los bancales yermos hasta reencontrarlo justo cuando penetra en un bonito y abundante carrascal. Llegamos el PR CV-75 13 y por la cresta que da al gemado valle de la Pobla de Benifass\u00e0, lo tomamos en direcci\u00f3n SE. Avanzamos cerca de la loma cumbre hasta plantarnos en el cabezal de la sierra de la Creu. En d\u00edas claros, se otea una profunda perspectiva que se alarga hacia las monta\u00f1as del Maestrazgo y de Teruel. Continuamos cresteando hacia levante por un agreste tramo rocoso, disfrutando en todo momento de vistas dilatadas, encarandonos hacia el valle de la Pobla de Benifass\u00e0 anteriormente encarados hacia el valle del r\u00edo Cervol y las molas de Bel. En este lado de la solana, tenemos en primer t\u00e9rmino la emboscado y salvaje barranco de la Borja.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77443b4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"77443b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b97a364\" data-id=\"b97a364\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-135d9e6 elementor-widget elementor-widget-text-editor\" data-id=\"135d9e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Descendemos por un paso rocoso rodeados de acantilados que le dan un gran atractivo. Pasado un collado, mudamos a la umbr\u00eda y la senda se hace m\u00e1s amable y menos pedregosa. En el collado del Xumador, un buen lugar para yacer un rato, llegamos al camino de Bel a la Pobla. Continuamos en la misma direcci\u00f3n por la loma hasta al era de Bel donde encontramos la pista de Bel al mas de n&#8217;Insa que se vislumbra ladera all\u00e1. Bajamos r\u00e1pidamente cara al norte, primero por un paso ancho y luego por una senda magn\u00edfica que va haciendo eses por el bosque de la umbr\u00eda de la Pobla.<\/br>\n<\/br>\nNos acercamos a la Pobla de Benifass\u00e0 por bancales de almendros abandonados y seguidamente por el cauce del barranco de Bel. Una vez estamos debajo de las casas, seguimos el barranco de la izquierda y hacemos hacia la fuente de Lluny, donde hay una sombreada \u00e1rea de ocio. La capital de la Tinen\u00e7a se encuentra construida en medio de la extensa depresi\u00f3n circular, rodeada al sur por la sierra de la Creu y al norte por las alturas del Boixar y de Fredes. Los callejones de la Pobla son pintorescos y merecen un tranquilo paseo.<\/h5>\n<\/br>\n<h4><span style=\"color: #000000;\"><u>EL VALLE DE LA POBLA DE BENIFASS\u00c0 Y LOS ESTRETS DEL RIU VERD<\/u><\/span><\/h4>\n<h5>Otra vez estamos en el barranco de debajo las casas del pueblo para seguir el PR 75 3.1 que nos acercar\u00e1 al pueblo del Bellestar. Entronque con la carretera que no tardaremos en abandonar por un sendero en descenso. Encontramos el desv\u00edo que por la izquierda nos llevar\u00e1 en diez minutos al altivo pueblo del Bellestar. Seguimos, sin embargo, por el ramal que baja hasta el cauce del r\u00edo Verd. Aqu\u00ed tenemos que desterrar los senderos subidizos y seguir hundidos entre los riscos alterosos que cierran el paso del r\u00edo. Estamos en los Estrets, otra garganta espectacular que hay que franquear por un guijarral del mismo cauce del r\u00edo Verd. Luego, encontramos a la izquierda un paso desembrozado que gana un poco de altura y se acerca al acantilado. Aqu\u00ed abandonamos el ramal que monta al Bellestar y proseguimos r\u00edo abajo.<\/br>\n<\/br>\nEl paraje del r\u00edo Verd es sumamente agreste, el bosque tiene un car\u00e1cter netamente mediterr\u00e1neo ya que hemos perdido mucha altura. El camino trillado nos lleva a una pista que circula paralela al cauce del r\u00edo y que lo cruza un par de vueltas. Remontamos en una lazada para salir un poco m\u00e1s all\u00e1 en las instalaciones de un centro de recuperaci\u00f3n de fauna salvaje, donde antes estaba el horno de Vidre. Estamos en la cola del embalse de Ulldecona. Justo pasadas las \u00faltimas edificaciones y antes de subir a la carretera, debemos decantarnos por un sendero arreglado hace poco que circula por la orilla norte del embalse, casi a nivel de las aguas. Disfrutamos de un hermoso espect\u00e1culo acu\u00e1tico: las aguas azuladas y de la frondosa vegetaci\u00f3n de las laderas se diluyen en la luz sesgada de la tarde. Hacemos hacia un \u00e1rea de recreo, lugar expreso para hacer un buen chapuz\u00f3n en las aguas tranquilas del embalse. El sendero sigue junto al agua hasta salir al puente y la toma del embalse. Punto y final de esta maravillosa vuelta por la Tinen\u00e7a de Benifass\u00e0.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-307b427 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"307b427\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e9be91\" data-id=\"1e9be91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfc91bf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cfc91bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db79cdf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"db79cdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0bef0c5\" data-id=\"0bef0c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef0283b elementor-widget elementor-widget-text-editor\" data-id=\"ef0283b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #000000;\"><u>TIEMPO ACONSEJABLE Y DIFICULTAD DE LA RUTA<\/u><\/span><\/h4>\n<h5>La primavera es la \u00e9poca m\u00e1s aconsejable, el d\u00eda es largo y el paisaje verde y florido. Tambi\u00e9n oto\u00f1o es buen momento. En invierno podemos encontrar nieve; y la niebla y el cierzo pueden dificultar la marcha. Casi todos los caminos por los que transcurre la ruta corresponden a PR, con se\u00f1ales amarillas y blancas; hay tramos del GR 7. Otros caminos est\u00e1n se\u00f1alizados con hitos de piedra y arreglados por los servicios del parque natural de la Tinen\u00e7a. S\u00f3lo son perdedores la colada del Mas Blanc y el paso del Tossal dels Tres Reis en la sierra Pelada, que se hace sin camino.<\/h5>\n<\/br>\n<h4><span style=\"color: #000000;\"><u>AGUA Y APROVISIONAMIENTO<\/u><\/span><\/h4>\n<h5>Encontraremos fuentes con agua segura en todos los pueblos del recorrido. Otros son pozos o fuentes con agua m\u00e1s incierta, como el pozo del mas Blanc, el r\u00edo Escalona (bajo el Maset), la fuente del Mas de Boix, los colmillos de la Gatellera y los pozos del mas de les Pruneres. Encontraremos bares restaurantes en todos los pueblos. Sobre todo nos servir\u00e1n para la comida del segundo y tercer d\u00eda, los de Castell de Cabres y la Pobla de Benifass\u00e0, respectivamente. Tenemos que contar que la comida de la primera jornada la haremos de mochila, ya que Fredes se encuentra muy al comienzo del recorrido.<\/h5>\n<\/br>\n<h4><span style=\"color: #000000;\"><u>CARTOGRAF\u00cdA<\/u><\/span><\/h4>\n<h5>Mapa y gu\u00eda excursionista de la Tinen\u00e7a de Benifass\u00e0. Escala 1:30.000. Tossal Cartografies, 2017<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65fe9af elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"65fe9af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b5eaa6\" data-id=\"8b5eaa6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50cdc7b elementor-widget elementor-widget-image\" data-id=\"50cdc7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"900\" src=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-05.jpg\" class=\"attachment-full size-full wp-image-11123\" alt=\"\" srcset=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-05.jpg 2000w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-05-300x135.jpg 300w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-05-1024x461.jpg 1024w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-05-768x346.jpg 768w, https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-05-1536x691.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">El mas de les Pruneres queda hundido en la cabecera del barranco (\u00a9 Josep Lorman)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa8f872 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"aa8f872\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf94727\" data-id=\"cf94727\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55d91d7 elementor-widget elementor-widget-spacer\" data-id=\"55d91d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0974111 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0974111\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc55e81\" data-id=\"cc55e81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29dcfc6 elementor-widget elementor-widget-image\" data-id=\"29dcfc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Ignasi-Planas-NW.jpg\" class=\"attachment-full size-full wp-image-11099\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dff6861 elementor-widget elementor-widget-text-editor\" data-id=\"dff6861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>IGNASI PLANAS DE MART\u00cd<\/h4>\n<h5>Ge\u00f3grafo que pisa la monta\u00f1a buscando caminos solitarios y paisajes rec\u00f3nditos. Ha publicado las gu\u00edas del Alt Gai\u00e0 y de las Muntanyes de Prades, de otros libros de tem\u00e1tica geogr\u00e1fica y art\u00edculos en diferentes revistas de monta\u00f1a.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5916d8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c5916d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eaf7d1c\" data-id=\"eaf7d1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4f2400 elementor-widget elementor-widget-spacer\" data-id=\"a4f2400\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d03f068 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d03f068\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67197d5\" data-id=\"67197d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43b22c2 elementor-widget elementor-widget-heading\" data-id=\"43b22c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><font color=\"#999999\"><u>Por si quieres compartir esta cr\u00f3nica<\/u><\/font><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-691fa33 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"691fa33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45d5ec7\" data-id=\"45d5ec7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75ed3c8 elementor-share-buttons--view-icon elementor-share-buttons--skin-framed elementor-share-buttons--shape-circle elementor-share-buttons--color-custom elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"75ed3c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_telegram\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en telegram\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-telegram\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_pinterest\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en pinterest\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-pinterest\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-whatsapp\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_print\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en print\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-print\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8892df elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f8892df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70b735e\" data-id=\"70b735e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cefc0b1 elementor-widget elementor-widget-spacer\" data-id=\"cefc0b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-391413e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"391413e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b0a7b6\" data-id=\"2b0a7b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2f0e7a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d2f0e7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-223888a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"223888a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ff790b\" data-id=\"0ff790b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69c2737 elementor-widget elementor-widget-heading\" data-id=\"69c2737\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><u>ART\u00cdCULOS Y RUTAS RELACIONADOS<\/u><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54618ba elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"54618ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c9e1462\" data-id=\"c9e1462\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fc75e5 elementor-widget elementor-widget-spacer\" data-id=\"4fc75e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18c50ee elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"18c50ee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8780cf\" data-id=\"d8780cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a32b04 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6a32b04\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96d3b52\" data-id=\"96d3b52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44721d5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"44721d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5225fa5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5225fa5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb4c9cd\" data-id=\"eb4c9cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8dd506f elementor-widget elementor-widget-spacer\" data-id=\"8dd506f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 LA ESQUISITEZ DEL BAIX MAESTRAT Cr\u00f3nica escrita por IGNASI PLANAS DE MART\u00cd y publicada en la revista MUNTANYA n\u00famero 898 Un circuito de monta\u00f1a que recorre en tres jornadas las villas de esta regi\u00f3n solitaria del norte del Baix Maestrat. El primer d\u00eda subimos a Fredes y, por [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":11087,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[5126,7044],"tags":[5146,5148,7046,7048,7050],"class_list":["post-11130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","category-tinenca-benifassa-es-es","tag-cronicas-ca-es","tag-croniques-ca-es","tag-ignasi-planas-de-marti-es","tag-la-volta-a-la-tinenca-de-benifassa-es","tag-vuelta-a-la-tinenca-de-benifassa-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 - Rutes Entre Refugis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 - Rutes Entre Refugis\" \/>\n<meta property=\"og:description\" content=\"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 LA ESQUISITEZ DEL BAIX MAESTRAT Cr\u00f3nica escrita por IGNASI PLANAS DE MART\u00cd y publicada en la revista MUNTANYA n\u00famero 898 Un circuito de monta\u00f1a que recorre en tres jornadas las villas de esta regi\u00f3n solitaria del norte del Baix Maestrat. El primer d\u00eda subimos a Fredes y, por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/\" \/>\n<meta property=\"og:site_name\" content=\"Rutes Entre Refugis\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-23T16:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-31T08:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Inici-NW.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ignasi Planas de Marti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ignasi Planas de Marti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"27 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/\"},\"author\":{\"name\":\"Ignasi Planas de Marti\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#\\\/schema\\\/person\\\/b7399f9a53f6fe655847967a61e14ce4\"},\"headline\":\"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0\",\"datePublished\":\"2021-02-23T16:13:00+00:00\",\"dateModified\":\"2023-10-31T08:32:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/\"},\"wordCount\":4766,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#\\\/schema\\\/person\\\/6e6f59c84210840610f19bafce39adc2\"},\"image\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Tinenca-de-Benifassa-Inici-NW.jpg\",\"keywords\":[\"Cr\u00f3nicas\",\"Cr\u00f2niques\",\"Ignasi Planas de Marti\",\"La Volta a la Tinen\u00e7a de Benifass\u00e0\",\"Vuelta a la Tinen\u00e7a de Benifass\u00e0\"],\"articleSection\":[\"Blog.\",\"Tinen\u00e7a Benifassa.\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/\",\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/\",\"name\":\"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 - Rutes Entre Refugis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Tinenca-de-Benifassa-Inici-NW.jpg\",\"datePublished\":\"2021-02-23T16:13:00+00:00\",\"dateModified\":\"2023-10-31T08:32:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Tinenca-de-Benifassa-Inici-NW.jpg\",\"contentUrl\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Tinenca-de-Benifassa-Inici-NW.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/2021\\\/02\\\/23\\\/la-vuelta-a-la-tinenca-de-benifassa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/rutesentrerefugis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#website\",\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/\",\"name\":\"Rutes Entre Refugis\",\"description\":\"Caminant sota un nom\",\"publisher\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#\\\/schema\\\/person\\\/6e6f59c84210840610f19bafce39adc2\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rutesentrerefugis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#\\\/schema\\\/person\\\/6e6f59c84210840610f19bafce39adc2\",\"name\":\"Rutes Entre Refugis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Logo-200x200-1.jpg\",\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Logo-200x200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Logo-200x200-1.jpg\",\"width\":200,\"height\":200,\"caption\":\"Rutes Entre Refugis\"},\"logo\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Logo-200x200-1.jpg\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#\\\/schema\\\/person\\\/b7399f9a53f6fe655847967a61e14ce4\",\"name\":\"Ignasi Planas de Marti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/avatar_user_41_1683353969-96x96.jpg\",\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/avatar_user_41_1683353969-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/avatar_user_41_1683353969-96x96.jpg\",\"caption\":\"Ignasi Planas de Marti\"},\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/author\\\/ignasi-planas-de-marti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 - Rutes Entre Refugis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/","og_locale":"es_ES","og_type":"article","og_title":"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 - Rutes Entre Refugis","og_description":"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 LA ESQUISITEZ DEL BAIX MAESTRAT Cr\u00f3nica escrita por IGNASI PLANAS DE MART\u00cd y publicada en la revista MUNTANYA n\u00famero 898 Un circuito de monta\u00f1a que recorre en tres jornadas las villas de esta regi\u00f3n solitaria del norte del Baix Maestrat. El primer d\u00eda subimos a Fredes y, por [&hellip;]","og_url":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/","og_site_name":"Rutes Entre Refugis","article_published_time":"2021-02-23T16:13:00+00:00","article_modified_time":"2023-10-31T08:32:17+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Inici-NW.jpg","type":"image\/jpeg"}],"author":"Ignasi Planas de Marti","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ignasi Planas de Marti","Tiempo de lectura":"27 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/#article","isPartOf":{"@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/"},"author":{"name":"Ignasi Planas de Marti","@id":"https:\/\/rutesentrerefugis.com\/#\/schema\/person\/b7399f9a53f6fe655847967a61e14ce4"},"headline":"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0","datePublished":"2021-02-23T16:13:00+00:00","dateModified":"2023-10-31T08:32:17+00:00","mainEntityOfPage":{"@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/"},"wordCount":4766,"commentCount":0,"publisher":{"@id":"https:\/\/rutesentrerefugis.com\/#\/schema\/person\/6e6f59c84210840610f19bafce39adc2"},"image":{"@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/#primaryimage"},"thumbnailUrl":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Inici-NW.jpg","keywords":["Cr\u00f3nicas","Cr\u00f2niques","Ignasi Planas de Marti","La Volta a la Tinen\u00e7a de Benifass\u00e0","Vuelta a la Tinen\u00e7a de Benifass\u00e0"],"articleSection":["Blog.","Tinen\u00e7a Benifassa."],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/","url":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/","name":"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0 - Rutes Entre Refugis","isPartOf":{"@id":"https:\/\/rutesentrerefugis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/#primaryimage"},"image":{"@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/#primaryimage"},"thumbnailUrl":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Inici-NW.jpg","datePublished":"2021-02-23T16:13:00+00:00","dateModified":"2023-10-31T08:32:17+00:00","breadcrumb":{"@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/#primaryimage","url":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Inici-NW.jpg","contentUrl":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/03\/Tinenca-de-Benifassa-Inici-NW.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/2021\/02\/23\/la-vuelta-a-la-tinenca-de-benifassa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/rutesentrerefugis.com\/"},{"@type":"ListItem","position":2,"name":"LA VUELTA A LA TINEN\u00c7A DE BENIFASS\u00c0"}]},{"@type":"WebSite","@id":"https:\/\/rutesentrerefugis.com\/#website","url":"https:\/\/rutesentrerefugis.com\/","name":"Rutes Entre Refugis","description":"Caminant sota un nom","publisher":{"@id":"https:\/\/rutesentrerefugis.com\/#\/schema\/person\/6e6f59c84210840610f19bafce39adc2"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rutesentrerefugis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/rutesentrerefugis.com\/#\/schema\/person\/6e6f59c84210840610f19bafce39adc2","name":"Rutes Entre Refugis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2026\/06\/Logo-200x200-1.jpg","url":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2026\/06\/Logo-200x200-1.jpg","contentUrl":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2026\/06\/Logo-200x200-1.jpg","width":200,"height":200,"caption":"Rutes Entre Refugis"},"logo":{"@id":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2026\/06\/Logo-200x200-1.jpg"}},{"@type":"Person","@id":"https:\/\/rutesentrerefugis.com\/#\/schema\/person\/b7399f9a53f6fe655847967a61e14ce4","name":"Ignasi Planas de Marti","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/05\/avatar_user_41_1683353969-96x96.jpg","url":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/05\/avatar_user_41_1683353969-96x96.jpg","contentUrl":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2023\/05\/avatar_user_41_1683353969-96x96.jpg","caption":"Ignasi Planas de Marti"},"url":"https:\/\/rutesentrerefugis.com\/index.php\/author\/ignasi-planas-de-marti\/"}]}},"_links":{"self":[{"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/posts\/11130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/comments?post=11130"}],"version-history":[{"count":22,"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/posts\/11130\/revisions"}],"predecessor-version":[{"id":13751,"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/posts\/11130\/revisions\/13751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/media\/11087"}],"wp:attachment":[{"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/media?parent=11130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/categories?post=11130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/tags?post=11130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}