{"id":11842,"count":1,"description":"","link":"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/","name":"Steve Cracknell","slug":"steve-cracknell-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arxius de Steve Cracknell - Rutes Entre Refugis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de Steve Cracknell - Rutes Entre Refugis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Rutes Entre Refugis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/tag\\\/steve-cracknell-es\\\/\",\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/tag\\\/steve-cracknell-es\\\/\",\"name\":\"Arxius de Steve Cracknell - Rutes Entre Refugis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/tag\\\/steve-cracknell-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/index.php\\\/es\\\/tag\\\/steve-cracknell-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/rutesentrerefugis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steve Cracknell\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#website\",\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/\",\"name\":\"Rutes Entre Refugis\",\"description\":\"Caminant sota un nom\",\"publisher\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#\\\/schema\\\/person\\\/6e6f59c84210840610f19bafce39adc2\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rutesentrerefugis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/#\\\/schema\\\/person\\\/6e6f59c84210840610f19bafce39adc2\",\"name\":\"Rutes Entre Refugis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Logo-200x200-1.jpg\",\"url\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Logo-200x200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Logo-200x200-1.jpg\",\"width\":200,\"height\":200,\"caption\":\"Rutes Entre Refugis\"},\"logo\":{\"@id\":\"https:\\\/\\\/rutesentrerefugis.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Logo-200x200-1.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arxius de Steve Cracknell - Rutes Entre Refugis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/","og_locale":"es_ES","og_type":"article","og_title":"Arxius de Steve Cracknell - Rutes Entre Refugis","og_url":"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/","og_site_name":"Rutes Entre Refugis","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/","url":"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/","name":"Arxius de Steve Cracknell - Rutes Entre Refugis","isPartOf":{"@id":"https:\/\/rutesentrerefugis.com\/#website"},"breadcrumb":{"@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/rutesentrerefugis.com\/index.php\/es\/tag\/steve-cracknell-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/rutesentrerefugis.com\/"},{"@type":"ListItem","position":2,"name":"Steve Cracknell"}]},{"@type":"WebSite","@id":"https:\/\/rutesentrerefugis.com\/#website","url":"https:\/\/rutesentrerefugis.com\/","name":"Rutes Entre Refugis","description":"Caminant sota un nom","publisher":{"@id":"https:\/\/rutesentrerefugis.com\/#\/schema\/person\/6e6f59c84210840610f19bafce39adc2"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rutesentrerefugis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/rutesentrerefugis.com\/#\/schema\/person\/6e6f59c84210840610f19bafce39adc2","name":"Rutes Entre Refugis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2026\/06\/Logo-200x200-1.jpg","url":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2026\/06\/Logo-200x200-1.jpg","contentUrl":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2026\/06\/Logo-200x200-1.jpg","width":200,"height":200,"caption":"Rutes Entre Refugis"},"logo":{"@id":"https:\/\/rutesentrerefugis.com\/wp-content\/uploads\/2026\/06\/Logo-200x200-1.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/tags\/11842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rutesentrerefugis.com\/index.php\/wp-json\/wp\/v2\/posts?tags=11842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}